{"id":5445,"date":"2022-12-13T12:56:08","date_gmt":"2022-12-13T11:56:08","guid":{"rendered":"https:\/\/www.masialaportella.com\/?post_type=product&#038;p=5445"},"modified":"2022-12-13T13:04:13","modified_gmt":"2022-12-13T12:04:13","slug":"lot-ral-davinyo-despatlla-pota-i-embotits","status":"publish","type":"product","link":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/","title":{"rendered":"Lot Ral d&#8217;Aviny\u00f3 d&#8217;Espatlla pota i embotits"},"content":{"rendered":"<p><strong>Pack Nadal Masia La Portella<\/strong><\/p>\n<p>Lot d&#8217;Espatlla curada , Llonganissa, Fuet i Xori\u00e7. Ra\u00e7a r\u00fastica Ral d&#8217;Aviny\u00f3.<br \/>\n&#8211; Espatlla curada Ral d&#8217;Aviny\u00f3 (aprox 4,5 &#8211; 5 kg. la pe\u00e7a)<br \/>\n&#8211; Llonganissa Ral d&#8217;Aviny\u00f3 (aprox. 0,25-0,3 kg.)<br \/>\n&#8211; Fuet Ral d&#8217;Aviny\u00f3 (aprox. 0,17 kg.)<br \/>\n&#8211; Xori\u00e7 Ral d&#8217;Aviny\u00f3 (aprox 0,2 kg.)<\/p>\n<p><strong>Envasat:<\/strong><br \/>\nEmbotit Espatlla (granel)<br \/>\nEmbotits llonganissa, fuet y xori\u00e7 (envasat al buit)<\/p>\n<p><strong>Pes:<\/strong> 5,35 kg.<\/p>\n<p><strong>Ingredients:<\/strong><\/p>\n<div>\n<div>Espatlla curada: Espatlla de porc, sal, lactosa, sucre, conservants ( E-252, E-250 ) i antioxidants ( E-301 )<\/div>\n<div><\/div>\n<div>Llonganissa: Magre y espatlla de porc, tripa natural, sal, dextrosa, pebre, antioxidant (E-300), conservants (E-252, E-250).<\/div>\n<div><\/div>\n<div>Fuet: Magre y espatlla de porc, tripa natural, sal, dextrosa, pebre, antioxidant (E-300), conservants (E-252, E-250).<\/div>\n<div><\/div>\n<div>Xori\u00e7: Magre y panxeta de porc, tripa natural, pebre vermell, sal, dextrosa, dextrina, caiena, all, maltodextrina, extracte de pebre vermell ,<\/div>\n<div>estabilitzador ( E-451i), antioxidant ( E-316) i\u00a0 conservants ( E-252, E-250).<\/div>\n<\/div>\n<div><\/div>\n<p><strong>Al\u00e8rgens:<\/strong><br \/>\nEspatlla (cont\u00e9 lactosa)<br \/>\nLlonganissa (sense al.l\u00e8rgens)<br \/>\nFuet (sense al.l\u00e8rgens)<br \/>\nXori\u00e7 (sense al.l\u00e8rgens)<\/p>\n<p><strong>Caducitat:<\/strong><br \/>\nPaleta (12 mesos)<br \/>\nEmbotits llonganissa, fuet i xori\u00e7 (3 mesos)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lot maleta Ral d&#8217;Aviny\u00f3 amb Espatlla i embotits<\/p>\n","protected":false},"featured_media":6821,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[725,793],"product_tag":[],"class_list":["post-5445","product","type-product","status-publish","has-post-thumbnail","product_cat-lots-embotits-carn-fresca","product_cat-nadal","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pack Nadal Masia La Portella - mitj\u00e0 | La Portella<\/title>\n<meta name=\"description\" content=\"Pack Nadal Masia La Portella - Lot de 12 sobres de d&#039;Espatlla llescada Ral d&#039;Aviny\u00f3 (12 x 100gr = 1,2 kg)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pack Nadal Masia La Portella - mitj\u00e0 | La Portella\" \/>\n<meta property=\"og:description\" content=\"Pack Nadal Masia La Portella - Lot de 12 sobres de d&#039;Espatlla llescada Ral d&#039;Aviny\u00f3 (12 x 100gr = 1,2 kg)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/\" \/>\n<meta property=\"og:site_name\" content=\"Masia La Portella\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/raldavinyo\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-13T12:04:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.masialaportella.com\/wp-content\/uploads\/2022\/12\/lote-869009.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/nadal\\\/lot-ral-davinyo-despatlla-pota-i-embotits\\\/\",\"url\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/nadal\\\/lot-ral-davinyo-despatlla-pota-i-embotits\\\/\",\"name\":\"Pack Nadal Masia La Portella - mitj\u00e0 | La Portella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/nadal\\\/lot-ral-davinyo-despatlla-pota-i-embotits\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/nadal\\\/lot-ral-davinyo-despatlla-pota-i-embotits\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.masialaportella.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/869009-LOT-RAL-DAVINYO-MALETI-AMB-PECES-1.jpg\",\"datePublished\":\"2022-12-13T11:56:08+00:00\",\"dateModified\":\"2022-12-13T12:04:13+00:00\",\"description\":\"Pack Nadal Masia La Portella - Lot de 12 sobres de d'Espatlla llescada Ral d'Aviny\u00f3 (12 x 100gr = 1,2 kg)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/nadal\\\/lot-ral-davinyo-despatlla-pota-i-embotits\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/nadal\\\/lot-ral-davinyo-despatlla-pota-i-embotits\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/nadal\\\/lot-ral-davinyo-despatlla-pota-i-embotits\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.masialaportella.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/869009-LOT-RAL-DAVINYO-MALETI-AMB-PECES-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.masialaportella.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/869009-LOT-RAL-DAVINYO-MALETI-AMB-PECES-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/nadal\\\/lot-ral-davinyo-despatlla-pota-i-embotits\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\\\/\\\/www.masialaportella.com\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lot Ral d&#8217;Aviny\u00f3 d&#8217;Espatlla pota i embotits\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/\",\"name\":\"Masia La Portella\",\"description\":\"Tienda de Embutidos a Domicilio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/#organization\",\"name\":\"Mas\u00eda La Portella\",\"url\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.masialaportella.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cropped-MasiaLaPortella-fav-1.png\",\"contentUrl\":\"https:\\\/\\\/www.masialaportella.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/cropped-MasiaLaPortella-fav-1.png\",\"width\":512,\"height\":512,\"caption\":\"Mas\u00eda La Portella\"},\"image\":{\"@id\":\"https:\\\/\\\/www.masialaportella.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/raldavinyo\",\"https:\\\/\\\/www.instagram.com\\\/raldavinyo\\\/?hl=es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pack Nadal Masia La Portella - mitj\u00e0 | La Portella","description":"Pack Nadal Masia La Portella - Lot de 12 sobres de d'Espatlla llescada Ral d'Aviny\u00f3 (12 x 100gr = 1,2 kg)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/","og_locale":"ca_ES","og_type":"article","og_title":"Pack Nadal Masia La Portella - mitj\u00e0 | La Portella","og_description":"Pack Nadal Masia La Portella - Lot de 12 sobres de d'Espatlla llescada Ral d'Aviny\u00f3 (12 x 100gr = 1,2 kg)","og_url":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/","og_site_name":"Masia La Portella","article_publisher":"https:\/\/es-la.facebook.com\/raldavinyo","article_modified_time":"2022-12-13T12:04:13+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.masialaportella.com\/wp-content\/uploads\/2022\/12\/lote-869009.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/","url":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/","name":"Pack Nadal Masia La Portella - mitj\u00e0 | La Portella","isPartOf":{"@id":"https:\/\/www.masialaportella.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/#primaryimage"},"image":{"@id":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/#primaryimage"},"thumbnailUrl":"https:\/\/www.masialaportella.com\/wp-content\/uploads\/2022\/12\/869009-LOT-RAL-DAVINYO-MALETI-AMB-PECES-1.jpg","datePublished":"2022-12-13T11:56:08+00:00","dateModified":"2022-12-13T12:04:13+00:00","description":"Pack Nadal Masia La Portella - Lot de 12 sobres de d'Espatlla llescada Ral d'Aviny\u00f3 (12 x 100gr = 1,2 kg)","breadcrumb":{"@id":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/#primaryimage","url":"https:\/\/www.masialaportella.com\/wp-content\/uploads\/2022\/12\/869009-LOT-RAL-DAVINYO-MALETI-AMB-PECES-1.jpg","contentUrl":"https:\/\/www.masialaportella.com\/wp-content\/uploads\/2022\/12\/869009-LOT-RAL-DAVINYO-MALETI-AMB-PECES-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.masialaportella.com\/ca\/nadal\/lot-ral-davinyo-despatlla-pota-i-embotits\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.masialaportella.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Botiga","item":"https:\/\/www.masialaportella.com\/tienda\/"},{"@type":"ListItem","position":3,"name":"Lot Ral d&#8217;Aviny\u00f3 d&#8217;Espatlla pota i embotits"}]},{"@type":"WebSite","@id":"https:\/\/www.masialaportella.com\/ca\/#website","url":"https:\/\/www.masialaportella.com\/ca\/","name":"Masia La Portella","description":"Tienda de Embutidos a Domicilio","publisher":{"@id":"https:\/\/www.masialaportella.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.masialaportella.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.masialaportella.com\/ca\/#organization","name":"Mas\u00eda La Portella","url":"https:\/\/www.masialaportella.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.masialaportella.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.masialaportella.com\/wp-content\/uploads\/2019\/11\/cropped-MasiaLaPortella-fav-1.png","contentUrl":"https:\/\/www.masialaportella.com\/wp-content\/uploads\/2019\/11\/cropped-MasiaLaPortella-fav-1.png","width":512,"height":512,"caption":"Mas\u00eda La Portella"},"image":{"@id":"https:\/\/www.masialaportella.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/raldavinyo","https:\/\/www.instagram.com\/raldavinyo\/?hl=es"]}]}},"_links":{"self":[{"href":"https:\/\/www.masialaportella.com\/ca\/wp-json\/wp\/v2\/product\/5445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.masialaportella.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.masialaportella.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masialaportella.com\/ca\/wp-json\/wp\/v2\/comments?post=5445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masialaportella.com\/ca\/wp-json\/wp\/v2\/media\/6821"}],"wp:attachment":[{"href":"https:\/\/www.masialaportella.com\/ca\/wp-json\/wp\/v2\/media?parent=5445"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.masialaportella.com\/ca\/wp-json\/wp\/v2\/product_brand?post=5445"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.masialaportella.com\/ca\/wp-json\/wp\/v2\/product_cat?post=5445"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.masialaportella.com\/ca\/wp-json\/wp\/v2\/product_tag?post=5445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}